{"id":1544,"date":"2021-05-04T15:44:05","date_gmt":"2021-05-04T13:44:05","guid":{"rendered":"https:\/\/www.lefieu.fr\/?p=1544"},"modified":"2021-05-05T08:06:54","modified_gmt":"2021-05-05T06:06:54","slug":"les-tiques-attaquent","status":"publish","type":"post","link":"https:\/\/www.lefieu.fr\/index.php\/2021\/05\/04\/les-tiques-attaquent\/","title":{"rendered":"Les tiques attaquent !"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.lefieu.fr\/wp-content\/uploads\/2021\/05\/tique.jpg\" alt=\"\" class=\"wp-image-1545\" width=\"423\" height=\"238\" srcset=\"https:\/\/www.lefieu.fr\/wp-content\/uploads\/2021\/05\/tique.jpg 312w, https:\/\/www.lefieu.fr\/wp-content\/uploads\/2021\/05\/tique-300x169.jpg 300w\" sizes=\"auto, (max-width: 423px) 100vw, 423px\" \/><figcaption>R\u00e9pugnante, la tique peut aussi \u00eatre dangereuse<\/figcaption><\/figure><\/div>\n\n\n\n<p>Alors que s&#8217;annonce peu \u00e0 peu le d\u00e9confinement, chacun se met \u00e0 r\u00eaver de longues promenades en for\u00eat pour reprendre contact avec la nature&#8230;<\/p>\n\n\n\n<p>Absolument pas concern\u00e9s par la pand\u00e9mie, les tiques commencent aussi \u00e0 sortir et arpentent all\u00e8grement les zones bois\u00e9es humides ainsi que les herbes hautes de nos prairies. Comme les moustiques sont vecteurs de maladies, <strong>les tiques peuvent communiquer aux humains, grands ou petits, la <a href=\"https:\/\/www.vidal.fr\/sante\/voyage\/maladies-voyage\/borreliose-maladie-lyme\/symptomes.html\">maladie de Lyme<\/a>.<\/strong><\/p>\n\n\n\n<p>Cette infection est due \u00e0 une bact\u00e9rie que transmet la tique \u00e0 l&#8217;humain au moment d&#8217;une piq\u00fbre. Cette maladie n&#8217;est pas contagieuse mais n\u00e9cessite un traitement antibiotique en cas d&#8217;infection.<\/p>\n\n\n\n<p><strong>Dans les 3 \u00e0 30 jours apr\u00e8s la piq\u00fbre, la maladie peut appara\u00eetre sous la forme d&#8217;une plaque rouge et ronde qui s&#8217;\u00e9tend en cercle<\/strong> (voir photo ci-dessous). Si c&#8217;est le cas, il est n\u00e9cessaire de consulter rapidement un m\u00e9decin car, sans traitement, la maladie peut donner des signes neurologiques comme une paralysie du visage ou des atteintes des nerfs et du cerveau. De m\u00eame, les articulations ou plus rarement des organes comme le c\u0153ur peuvent \u00eatre affect\u00e9s par la maladie.<\/p>\n\n\n\n<p>Il faut donc se pr\u00e9munir de cette infection et prendre quelques mesures simples pour \u00e9viter de se faire piquer par les tiques. Lors des promenades, il est conseill\u00e9 de porter des v\u00eatements longs de couleur claire, un chapeau, porter des bottes ou glisser les bas de pantalons dans les chaussettes. Il faut \u00e9viter aussi d&#8217;attirer les tiques sur soi en s&#8217;allongeant directement sur le sol pour se reposer.<\/p>\n\n\n\n<p>Il existe \u00e9galement des r\u00e9pulsifs contre les insectes sur la peau&#8230;<\/p>\n\n\n\n<p><strong>D\u00e8s la fin de la promenade, une inspection attentive du corps est absolument n\u00e9cessaire.<\/strong> Il faut v\u00e9rifier le cuir chevelu, les aisselles, les plis des coudes et des genoux, les oreilles, le nombril et les r\u00e9gions g\u00e9nitales. Attention, les enfants sont des cibles privil\u00e9gi\u00e9es pour l&#8217;app\u00e9tit des tiques !<\/p>\n\n\n\n<p>En cas de pr\u00e9sence, il ne faut pas tenter de retirer l&#8217;animal avec les ongles, ni utiliser de produit. Pour l&#8217;enlever, soit \u00e0 la pince fine en la saisissant \u00e0 la base et en tirant sans tourner, soit \u00e0 l&#8217;aide d&#8217;un tire-tique (ou crochet \u00e0 tiques) qui permet de la saisir fermement et qui oblige la tique \u00e0 se d\u00e9crocher. Dans les deux cas, d\u00e8s  que la tique est \u00f4t\u00e9e de la peau, une d\u00e9sinfection \u00e0 l&#8217;aide d&#8217;un produit antiseptique est obligatoire. Ensuite, <strong>il faut imp\u00e9rativement assurer une surveillance de la zone piqu\u00e9e. Si une plaque rouge et ronde appara\u00eet, consulter rapidement votre m\u00e9decin.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.lefieu.fr\/wp-content\/uploads\/2021\/05\/th.jpg\" alt=\"\" class=\"wp-image-1547\" width=\"402\" height=\"269\"\/><figcaption>Ne pas h\u00e9siter \u00e0 consulter un m\u00e9decin<\/figcaption><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Alors que s&#8217;annonce peu \u00e0 peu le d\u00e9confinement, chacun se met \u00e0 r\u00eaver de longues promenades en for\u00eat pour reprendre contact avec la nature&#8230; Absolument pas concern\u00e9s par la pand\u00e9mie, les tiques commencent aussi \u00e0 sortir et arpentent all\u00e8grement les zones bois\u00e9es humides ainsi que les herbes hautes de nos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1545,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informations"],"_links":{"self":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/1544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1544"}],"version-history":[{"count":2,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/1544\/revisions"}],"predecessor-version":[{"id":1549,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/1544\/revisions\/1549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/media\/1545"}],"wp:attachment":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}