{"id":3150,"date":"2023-08-23T08:00:13","date_gmt":"2023-08-23T06:00:13","guid":{"rendered":"https:\/\/www.lefieu.fr\/?p=3150"},"modified":"2023-08-23T08:00:15","modified_gmt":"2023-08-23T06:00:15","slug":"smicval-modification-dhoraires","status":"publish","type":"post","link":"https:\/\/www.lefieu.fr\/index.php\/2023\/08\/23\/smicval-modification-dhoraires\/","title":{"rendered":"SMICVAL : Modification d&#8217;horaires"},"content":{"rendered":"\n<p>En raison des fortes chaleurs et pour prot\u00e9ger les agents du Smicval, les horaires des collectes ainsi que ceux des P\u00f4les Recyclage pour toute la semaine prochaine et jusqu&#8217;au 26 ao\u00fbt 2023 sont modifi\u00e9s :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pour <strong>les collectes d\u2019apr\u00e8s-midi<\/strong> : passage en soir\u00e9e. D\u00e9part des \u00e9quipes \u00e0 18h au lieu de 12h. Les habitants devront laisser les bacs \u00e0 l\u2019ext\u00e9rieur, jusqu\u2019au passage de la benne\u00a0pr\u00e9vue <strong>entre 18h et minuit.<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pour les <strong>P\u00f4les Recyclage<\/strong> : <strong>ouverture de 7h \u00e0 14h en continu du lundi au samedi<\/strong>. <em>Les vendredi 25 ao\u00fbt et samedi 26 ao\u00fbt, les P\u00f4les Recyclage sont ouverts de 7h \u00e0 14h en continu s<span style=\"text-decoration: underline;\">ur rendez-vous uniquement.<\/span><\/em><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>En raison des fortes chaleurs et pour prot\u00e9ger les agents du Smicval, les horaires des collectes ainsi que ceux des P\u00f4les Recyclage pour toute la semaine prochaine et jusqu&#8217;au 26 ao\u00fbt 2023 sont modifi\u00e9s :<\/p>\n","protected":false},"author":1,"featured_media":755,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-3150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informations"],"_links":{"self":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/3150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3150"}],"version-history":[{"count":2,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/3150\/revisions"}],"predecessor-version":[{"id":3152,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/3150\/revisions\/3152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/media\/755"}],"wp:attachment":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}