{"id":3807,"date":"2025-02-11T17:13:32","date_gmt":"2025-02-11T16:13:32","guid":{"rendered":"https:\/\/www.lefieu.fr\/?p=3807"},"modified":"2025-02-11T17:26:25","modified_gmt":"2025-02-11T16:26:25","slug":"mobilisation-patrimoine-tous-acteurs","status":"publish","type":"post","link":"https:\/\/www.lefieu.fr\/index.php\/2025\/02\/11\/mobilisation-patrimoine-tous-acteurs\/","title":{"rendered":"Mobilisation &#8220;Patrimoine&#8221;: Tous acteurs !"},"content":{"rendered":"\n<p><strong>Le projet collectif pou un \u00e9difice communal au c\u0153ur du village.<\/strong><\/p>\n\n\n\n<p>Parmi les b\u00e2timents communaux, l&#8217;\u00e9glise Saint-Nicolas est bien plus qu\u2019un \u00e9difice religieux ; elle est un t\u00e9moin de l&#8217;histoire, un rep\u00e8re dans le village, un patrimoine que les F\u00e9odiens doivent pr\u00e9server ensemble. Depuis plusieurs ann\u00e9es, la municipalit\u00e9 s\u2019engage activement dans l&#8217;entretien de son patrimoine communal et, pour l&#8217;\u00e9glise, dans sa restauration avec une premi\u00e8re phase de travaux qui a permis une partie de son ravalement, la remise en \u00e9tat la toiture, la modernisation de l\u2019\u00e9clairage et du chauffage, et ces derniers mois, la restauration de la statue de Saint-Nicolas, pi\u00e8ce ma\u00eetresse de cet \u00e9difice.<\/p>\n\n\n\n<p>En ce d\u00e9but 2025, un nouveau chapitre s\u2019ouvre : la r\u00e9habilitation de l\u2019int\u00e9rieur de l\u2019\u00e9glise pour lui redonner son \u00e9clat d\u2019antan. C\u2019est un d\u00e9fi ambitieux, mais passionnant, que la municipalit\u00e9 souhaite relever collectivement.<\/p>\n\n\n\n<p><strong>Un projet par \u00e9tapes, un engagement sur le long terme.<\/strong><\/p>\n\n\n\n<p>Les premi\u00e8res interventions ont permis de s\u00e9curiser et moderniser le b\u00e2timent. La toiture a \u00e9t\u00e9 refaite, les fa\u00e7ades mises en lumi\u00e8re et la mise aux normes \u00e9lectriques a \u00e9t\u00e9 achev\u00e9e. Mais au-del\u00e0 de ces aspects techniques, c\u2019est l\u2019\u00e2me du b\u00e2timent qu&#8217;il faut faire revivre.<\/p>\n\n\n\n<p>Un \u00e9l\u00e9ment embl\u00e9matique de cette d\u00e9marche est la restauration de la statue en bois de Saint-Nicolas datant du XII\u1d49 si\u00e8cle. Fragilis\u00e9e par les si\u00e8cles, elle a \u00e9t\u00e9 confi\u00e9e \u00e0 la restauratrice bordelaise <strong><a href=\"https:\/\/www.aline-raux.com\/\">Aline Raux<\/a><\/strong>, qui lui redonne actuellement toute sa splendeur. Un travail minutieux de nettoyage, de consolidation du bois, de refixage des couleurs et de restitution des parties manquantes est en cours. D\u2019ici quelques semaines, cette statue restaur\u00e9e retrouvera sa place dans l&#8217;\u00e9glise, symbole de l&#8217;engagement \u00e0 pr\u00e9server ce patrimoine inestimable.<\/p>\n\n\n\n<p>L&#8217;ensemble de ces travaux prennent ainsi l\u2019exemple de la restauration du retable du XVIII\u1d49 si\u00e8cle en bois, situ\u00e9 dans le bas-c\u00f4t\u00e9 droit de l\u2019\u00e9glise. Gr\u00e2ce \u00e0 l\u2019initiative de l\u2019abb\u00e9 Henri David, cette pi\u00e8ce remarquable a \u00e9t\u00e9 restaur\u00e9e en 1999, retrouvant alors l\u2019\u00e9clat de ses peintures en imitation marbre et de ses dorures d\u2019origine. Ce travail minutieux avait permis de redonner \u00e0 cet \u00e9l\u00e9ment son cachet d\u2019antan et aujourd\u2019hui encore, il t\u00e9moigne de l\u2019importance de cet engagement collectif pour pr\u00e9server cet \u00e9difice.<\/p>\n\n\n\n<p><strong>Un projet collectif qui concerne les habitants.<\/strong><\/p>\n\n\n\n<p>La sauvegarde de l\u2019\u00e9glise Saint-Nicolas repose sur une mobilisation ancienne. D\u00e8s 1996, une association d\u00e9di\u00e9e \u00e0 sa protection et \u00e0 sa mise en valeur avait \u00e9t\u00e9 cr\u00e9\u00e9e : le Comit\u00e9 de Soutien de l\u2019\u00c9glise Saint-Nicolas de Le Fieu. Aujourd\u2019hui, les \u00e9lus veulent donner un nouvel \u00e9lan \u00e0 cette d\u00e9marche en structurant une dynamique moderne et collective.<\/p>\n\n\n\n<p><strong>Pour mener \u00e0 bien cette r\u00e9habilitation, la commune a besoin de toutes les \u00e9nergies.\u00a0<\/strong><\/p>\n\n\n\n<p>Des habitants passionn\u00e9s se sont d\u00e9j\u00e0 mobilis\u00e9s en explorant les archives d\u00e9partementales pour retracer l\u2019histoire du b\u00e2timent et de ses \u00e9volutions. Leur travail est une ressource pr\u00e9cieuse qui guidera les prochaines \u00e9tapes de la restauration.<\/p>\n\n\n\n<p>Mais au-del\u00e0 des recherches historiques, c\u2019est ensemble qu&#8217;il faut construire pour la p\u00e9rennit\u00e9 de l&#8217;\u00e9glise. C\u2019est pourquoi les \u00e9lus proposent la cr\u00e9ation d\u2019une nouvelle association d\u00e9di\u00e9e \u00e0 sa sauvegarde, qui f\u00e9d\u00e9rera les habitants, organisera des actions de sensibilisation et mobilisera des financements compl\u00e9mentaires <em>(subventions, m\u00e9c\u00e9nat, souscriptions locales)<\/em>.<\/p>\n\n\n\n<p><strong>Rejoignez cette belle aventure !<\/strong><\/p>\n\n\n\n<p>Les F\u00e9odiens qui souhaitent participer \u00e0 ce projet sont invit\u00e9s \u00e0 une <strong><span style=\"text-decoration: underline;\">r\u00e9union le 18 f\u00e9vrier \u00e0 10h dans la salle du conseil municipal<\/span><\/strong>. Ce sera l&#8217;occasion pour \u00e9changer sur les prochaines \u00e9tapes du projet, proposer des pistes d&#8217;actions et structurer cette mobilisation.<\/p>\n\n\n\n<p>L\u2019\u00e9glise Saint-Nicolas est un bien communal, un lieu de m\u00e9moire et de transmission. Gr\u00e2ce \u00e0 l\u2019implication des \u00e9lus, des habitants et des amoureux du patrimoine, ce projet prend vie. Ensemble, redonnons \u00e0 ce t\u00e9moignage du pass\u00e9 toute sa place d&#8217;avenir dans le c\u0153ur du village !<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><span style=\"text-decoration: underline;\">Rendez-vous le mardi 18 f\u00e9vrier 2025 \u00e0 10h00 (salle du Conseil)<\/span><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"641\" height=\"650\" src=\"https:\/\/www.lefieu.fr\/wp-content\/uploads\/2021\/12\/2021-12-01_20h23_15.png\" alt=\"\" class=\"wp-image-1953\" style=\"width:833px;height:auto\" srcset=\"https:\/\/www.lefieu.fr\/wp-content\/uploads\/2021\/12\/2021-12-01_20h23_15.png 641w, https:\/\/www.lefieu.fr\/wp-content\/uploads\/2021\/12\/2021-12-01_20h23_15-296x300.png 296w\" sizes=\"auto, (max-width: 641px) 100vw, 641px\" \/><\/figure>\n<\/div>\n\n\n<p>Eglise St-Nicolas, LE FIEU <\/p>\n\n\n\n<p><sup><em>(Photo A.R.)<\/em><\/sup><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le projet collectif pou un \u00e9difice communal au c\u0153ur du village. Parmi les b\u00e2timents communaux, l&#8217;\u00e9glise Saint-Nicolas est bien plus qu\u2019un \u00e9difice religieux ; elle est un t\u00e9moin de l&#8217;histoire, un rep\u00e8re dans le village, un patrimoine que les F\u00e9odiens doivent pr\u00e9server ensemble. Depuis plusieurs ann\u00e9es, la municipalit\u00e9 s\u2019engage activement [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1953,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[6,12],"tags":[],"class_list":["post-3807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informations","category-municipalite"],"_links":{"self":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/3807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3807"}],"version-history":[{"count":5,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/3807\/revisions"}],"predecessor-version":[{"id":3812,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/3807\/revisions\/3812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/media\/1953"}],"wp:attachment":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}