{"id":4112,"date":"2025-08-08T18:57:06","date_gmt":"2025-08-08T16:57:06","guid":{"rendered":"https:\/\/www.lefieu.fr\/?p=4112"},"modified":"2025-08-08T18:57:07","modified_gmt":"2025-08-08T16:57:07","slug":"des-filles-bien-en-selle","status":"publish","type":"post","link":"https:\/\/www.lefieu.fr\/index.php\/2025\/08\/08\/des-filles-bien-en-selle\/","title":{"rendered":"Des filles bien en selle !"},"content":{"rendered":"\n<p>Article pr\u00e9c\u00e9dent : <a href=\"https:\/\/www.lefieu.fr\/index.php\/2025\/05\/08\/mal-barrees-mais-bien-parties\/\">https:\/\/www.lefieu.fr\/index.php\/2025\/05\/08\/mal-barrees-mais-bien-parties\/<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un grand bravo aux &#8220;Mal-Barr\u00e9es&#8221; de l\u2019\u00c9curie du Petit Barreau !<\/h3>\n\n\n\n<p>Elles sont rentr\u00e9es du Championnat de France, fatigu\u00e9es mais avec le sourire, et la commune de LE FIEU tient \u00e0 leur adresser ses plus sinc\u00e8res f\u00e9licitations. Elle est fi\u00e8re de les avoir accompagn\u00e9es dans cette belle aventure et ravie de pouvoir saluer leur parcours exceptionnel.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Une belle r\u00e9ussite malgr\u00e9 l&#8217;impr\u00e9vu<\/h3>\n\n\n\n<p>Les &#8220;Mal-Barr\u00e9es&#8221; ont r\u00e9alis\u00e9 une saison remarquable en se qualifiant pour le Championnat de France. Leur performance \u00e0 l&#8217;\u00e9preuve d&#8217;orientation, avec un score impressionnant de <strong>290\/300<\/strong>, les a plac\u00e9es tout pr\u00e8s du podium, \u00e0 seulement 6 points des premi\u00e8res ! Un r\u00e9sultat qui t\u00e9moigne de leur talent et qui laisse entrevoir un avenir plein de promesses.<\/p>\n\n\n\n<p>Malheureusement, le sport \u00e9questre r\u00e9serve parfois son lot d&#8217;impr\u00e9vus. Guernika, la jument de M\u00e9lissa, s&#8217;est bless\u00e9e le samedi matin, emp\u00eachant l&#8217;\u00e9quipe de prendre le d\u00e9part dans les meilleures conditions. Comme elles le disent si bien, \u00ab Un seul \u00eatre vous manque et tout est d\u00e9peupl\u00e9\u2026 \u00bb.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Un exemple de t\u00e9nacit\u00e9 et de fair-play<\/h3>\n\n\n\n<p>Malgr\u00e9 cet obstacle, les &#8220;Mal-Barr\u00e9es&#8221; n&#8217;ont pas baiss\u00e9 les bras. Elles ont fait preuve d&#8217;une t\u00e9nacit\u00e9, d&#8217;un respect et d&#8217;une coh\u00e9sion admirables. Elles ont poursuivi la comp\u00e9tition avec courage, terminant \u00e0 une tr\u00e8s honorable 14e place sur 25.<\/p>\n\n\n\n<p>Au nom de la commune, le Maire et le Conseil municipal tiennent \u00e0 saluer leur engagement et leur esprit d&#8217;\u00e9quipe exemplaire. Elles ont port\u00e9 haut les couleurs de Le Fieu, faisant preuve de gr\u00e2ce et de passion, tout en respectant leurs fid\u00e8les compagnons \u00e0 quatre pattes.<\/p>\n\n\n\n<p>La mairie est fi\u00e8re d&#8217;avoir soutenu cette \u00e9quipe inspirante. Bravo aux &#8220;Mal-Barr\u00e9es&#8221;, cette aventure ne fait que commencer; le podium sera pour la prochaine fois, c&#8217;est s\u00fbr !<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/www.lefieu.fr\/wp-content\/uploads\/2025\/08\/528623102_1294700812008728_1157367522764471054_n.jpg\" alt=\"\" class=\"wp-image-4115\" srcset=\"https:\/\/www.lefieu.fr\/wp-content\/uploads\/2025\/08\/528623102_1294700812008728_1157367522764471054_n.jpg 600w, https:\/\/www.lefieu.fr\/wp-content\/uploads\/2025\/08\/528623102_1294700812008728_1157367522764471054_n-300x169.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">Sur la piste de la victoire !<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/www.lefieu.fr\/wp-content\/uploads\/2025\/08\/529307357_1294700845342058_1735568228430821827_n.jpg\" alt=\"\" class=\"wp-image-4114\" srcset=\"https:\/\/www.lefieu.fr\/wp-content\/uploads\/2025\/08\/529307357_1294700845342058_1735568228430821827_n.jpg 450w, https:\/\/www.lefieu.fr\/wp-content\/uploads\/2025\/08\/529307357_1294700845342058_1735568228430821827_n-225x300.jpg 225w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><figcaption class=\"wp-element-caption\">Il faut aller de l&#8217;avant.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"338\" height=\"600\" src=\"https:\/\/www.lefieu.fr\/wp-content\/uploads\/2025\/08\/528460177_1294700882008721_2303404574004231365_n.jpg\" alt=\"\" class=\"wp-image-4116\" srcset=\"https:\/\/www.lefieu.fr\/wp-content\/uploads\/2025\/08\/528460177_1294700882008721_2303404574004231365_n.jpg 338w, https:\/\/www.lefieu.fr\/wp-content\/uploads\/2025\/08\/528460177_1294700882008721_2303404574004231365_n-169x300.jpg 169w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\" \/><figcaption class=\"wp-element-caption\">On y croit&#8230;<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"338\" height=\"600\" src=\"https:\/\/www.lefieu.fr\/wp-content\/uploads\/2025\/08\/528871223_1294700768675399_1133738082167046290_n.jpg\" alt=\"\" class=\"wp-image-4117\" srcset=\"https:\/\/www.lefieu.fr\/wp-content\/uploads\/2025\/08\/528871223_1294700768675399_1133738082167046290_n.jpg 338w, https:\/\/www.lefieu.fr\/wp-content\/uploads\/2025\/08\/528871223_1294700768675399_1133738082167046290_n-169x300.jpg 169w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\" \/><figcaption class=\"wp-element-caption\">Malgr\u00e9 une certaine d\u00e9ception, les filles gardent le sourire !<\/figcaption><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Article pr\u00e9c\u00e9dent : https:\/\/www.lefieu.fr\/index.php\/2025\/05\/08\/mal-barrees-mais-bien-parties\/ Un grand bravo aux &#8220;Mal-Barr\u00e9es&#8221; de l\u2019\u00c9curie du Petit Barreau ! Elles sont rentr\u00e9es du Championnat de France, fatigu\u00e9es mais avec le sourire, et la commune de LE FIEU tient \u00e0 leur adresser ses plus sinc\u00e8res f\u00e9licitations. Elle est fi\u00e8re de les avoir accompagn\u00e9es dans cette [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4013,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[14,6],"tags":[],"class_list":["post-4112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-associations","category-informations"],"_links":{"self":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/4112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/comments?post=4112"}],"version-history":[{"count":3,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/4112\/revisions"}],"predecessor-version":[{"id":4119,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/4112\/revisions\/4119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/media\/4013"}],"wp:attachment":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/media?parent=4112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/categories?post=4112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/tags?post=4112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}