{"id":978,"date":"2020-09-29T20:57:05","date_gmt":"2020-09-29T18:57:05","guid":{"rendered":"http:\/\/www.lefieu.fr\/?p=978"},"modified":"2020-10-04T18:52:23","modified_gmt":"2020-10-04T16:52:23","slug":"degradations-volontaires-sur-la-vc-7","status":"publish","type":"post","link":"https:\/\/www.lefieu.fr\/index.php\/2020\/09\/29\/degradations-volontaires-sur-la-vc-7\/","title":{"rendered":"D\u00e9gradations volontaires sur la VC 7 ?"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.lefieu.fr\/wp-content\/uploads\/2020\/09\/IMG-0066-2-768x1024.jpg\" alt=\"\" class=\"wp-image-979\" width=\"373\" height=\"497\" srcset=\"https:\/\/www.lefieu.fr\/wp-content\/uploads\/2020\/09\/IMG-0066-2-768x1024.jpg 768w, https:\/\/www.lefieu.fr\/wp-content\/uploads\/2020\/09\/IMG-0066-2-225x300.jpg 225w, https:\/\/www.lefieu.fr\/wp-content\/uploads\/2020\/09\/IMG-0066-2-1152x1536.jpg 1152w, https:\/\/www.lefieu.fr\/wp-content\/uploads\/2020\/09\/IMG-0066-2-1536x2048.jpg 1536w, https:\/\/www.lefieu.fr\/wp-content\/uploads\/2020\/09\/IMG-0066-2-scaled.jpg 1920w\" sizes=\"auto, (max-width: 373px) 100vw, 373px\" \/><figcaption>D\u00e9gradations inadmissibles<\/figcaption><\/figure><\/div>\n\n\n\n<p>Comme pr\u00e9vu et \u00e9voqu\u00e9 dans un pr\u00e9c\u00e9dent article, la voie communale n\u00b0 7 entre le lieu-dit &#8220;La Cabirotte&#8221; et la carri\u00e8re Lafarge a subi d&#8217;importants travaux de r\u00e9fection de chauss\u00e9e.<\/p>\n\n\n\n<p>Pr\u00e9voyant les pluies du week-end, l&#8217;entreprise charg\u00e9e des travaux y a r\u00e9alis\u00e9 un rev\u00eatement pour \u00e9tancher et prot\u00e9ger la voie des futures intemp\u00e9ries.<\/p>\n\n\n\n<p>Mais, il semble que des usagers peu scrupuleux, et enclin \u00e0 d\u00e9truire le travail fait, ont d\u00e9cid\u00e9 de s&#8217;amuser \u00e0 d\u00e9grader la surface de la route. Celle-ci n&#8217;ayant alors plus d&#8217;\u00e9tanch\u00e9it\u00e9, la pluie a largement p\u00e9n\u00e9tr\u00e9 le corps de chauss\u00e9e transform\u00e9 aujourd&#8217;hui en v\u00e9ritable matelas instable.<\/p>\n\n\n\n<p>Devant cette situation dangereuse pour la circulation, la mairie a pris un arr\u00eat\u00e9 interdisant toute utilisation de la VC 7 jusqu&#8217;\u00e0 nouvel ordre <em>(sauf riverains et services publics)<\/em>. <\/p>\n\n\n\n<p>La municipalit\u00e9 tient tout de m\u00eame \u00e0 faire savoir que ces situations de d\u00e9gradations gratuites monopolisent \u00e0 terme des finances communales non pr\u00e9vues qui, dans tous les cas, sont prises en compte par les imp\u00f4ts des habitants lorsque que l&#8217;on ne trouvent pas les auteurs de ces faits.<\/p>\n\n\n\n<p>Les \u00e9lus de la commune font donc appel \u00e0 la vigilance de chacun pour rep\u00e9rer les usagers malveillants qui prennent plaisir \u00e0 d\u00e9truire ce que d&#8217;autres font&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme pr\u00e9vu et \u00e9voqu\u00e9 dans un pr\u00e9c\u00e9dent article, la voie communale n\u00b0 7 entre le lieu-dit &#8220;La Cabirotte&#8221; et la carri\u00e8re Lafarge a subi d&#8217;importants travaux de r\u00e9fection de chauss\u00e9e. Pr\u00e9voyant les pluies du week-end, l&#8217;entreprise charg\u00e9e des travaux y a r\u00e9alis\u00e9 un rev\u00eatement pour \u00e9tancher et prot\u00e9ger la voie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-978","post","type-post","status-publish","format-standard","hentry","category-informations"],"_links":{"self":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/comments?post=978"}],"version-history":[{"count":4,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/978\/revisions"}],"predecessor-version":[{"id":984,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/978\/revisions\/984"}],"wp:attachment":[{"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/media?parent=978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/categories?post=978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lefieu.fr\/index.php\/wp-json\/wp\/v2\/tags?post=978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}